{"id":337,"count":1,"description":"","link":"https:\/\/frankrechsteiner.de\/en\/tag\/purpose-en\/","name":"Purpose","slug":"purpose-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Purpose Archives - frankrechsteiner.de<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Purpose Archives - frankrechsteiner.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frankrechsteiner.de\/en\/tag\/purpose-en\/\" \/>\n<meta property=\"og:site_name\" content=\"frankrechsteiner.de\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frankrechsteiner.de\/wp-content\/uploads\/2025\/04\/Executive-coaching-img-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1759\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/tag\\\/purpose-en\\\/\",\"url\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/tag\\\/purpose-en\\\/\",\"name\":\"Purpose Archives - frankrechsteiner.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/tag\\\/purpose-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/tag\\\/purpose-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Purpose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/\",\"name\":\"frankrechsteiner.de\",\"description\":\"CEO Advisory for the New Reality of Work\",\"publisher\":{\"@id\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/#\\\/schema\\\/person\\\/fc7d2ccc695caeb6276ccd7eedacdc96\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/frankrechsteiner.de\\\/en\\\/#\\\/schema\\\/person\\\/fc7d2ccc695caeb6276ccd7eedacdc96\",\"name\":\"Frank Rechsteiner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/frankrechsteiner.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Frank-Rechsteiner-Speaker.jpg\",\"url\":\"https:\\\/\\\/frankrechsteiner.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Frank-Rechsteiner-Speaker.jpg\",\"contentUrl\":\"https:\\\/\\\/frankrechsteiner.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Frank-Rechsteiner-Speaker.jpg\",\"width\":1171,\"height\":1600,\"caption\":\"Frank Rechsteiner\"},\"logo\":{\"@id\":\"https:\\\/\\\/frankrechsteiner.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Frank-Rechsteiner-Speaker.jpg\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/frankrechsteiner\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/FrankRechsteiner\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Purpose Archives - frankrechsteiner.de","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Purpose Archives - frankrechsteiner.de","og_url":"https:\/\/frankrechsteiner.de\/en\/tag\/purpose-en\/","og_site_name":"frankrechsteiner.de","og_image":[{"width":1920,"height":1759,"url":"https:\/\/frankrechsteiner.de\/wp-content\/uploads\/2025\/04\/Executive-coaching-img-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/frankrechsteiner.de\/en\/tag\/purpose-en\/","url":"https:\/\/frankrechsteiner.de\/en\/tag\/purpose-en\/","name":"Purpose Archives - frankrechsteiner.de","isPartOf":{"@id":"https:\/\/frankrechsteiner.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/frankrechsteiner.de\/en\/tag\/purpose-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/frankrechsteiner.de\/en\/tag\/purpose-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/frankrechsteiner.de\/en\/"},{"@type":"ListItem","position":2,"name":"Purpose"}]},{"@type":"WebSite","@id":"https:\/\/frankrechsteiner.de\/en\/#website","url":"https:\/\/frankrechsteiner.de\/en\/","name":"frankrechsteiner.de","description":"CEO Advisory for the New Reality of Work","publisher":{"@id":"https:\/\/frankrechsteiner.de\/en\/#\/schema\/person\/fc7d2ccc695caeb6276ccd7eedacdc96"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frankrechsteiner.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/frankrechsteiner.de\/en\/#\/schema\/person\/fc7d2ccc695caeb6276ccd7eedacdc96","name":"Frank Rechsteiner","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/frankrechsteiner.de\/wp-content\/uploads\/2026\/07\/Frank-Rechsteiner-Speaker.jpg","url":"https:\/\/frankrechsteiner.de\/wp-content\/uploads\/2026\/07\/Frank-Rechsteiner-Speaker.jpg","contentUrl":"https:\/\/frankrechsteiner.de\/wp-content\/uploads\/2026\/07\/Frank-Rechsteiner-Speaker.jpg","width":1171,"height":1600,"caption":"Frank Rechsteiner"},"logo":{"@id":"https:\/\/frankrechsteiner.de\/wp-content\/uploads\/2026\/07\/Frank-Rechsteiner-Speaker.jpg"},"sameAs":["https:\/\/www.linkedin.com\/in\/frankrechsteiner","https:\/\/www.youtube.com\/c\/FrankRechsteiner"]}]}},"_links":{"self":[{"href":"https:\/\/frankrechsteiner.de\/en\/wp-json\/wp\/v2\/tags\/337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frankrechsteiner.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/frankrechsteiner.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/frankrechsteiner.de\/en\/wp-json\/wp\/v2\/posts?tags=337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}